{"id":768289,"date":"2020-03-22T01:25:57","date_gmt":"2020-03-22T05:25:57","guid":{"rendered":""},"modified":"2026-06-23T18:35:23","modified_gmt":"2026-06-23T22:35:23","slug":"estudio-biblico-cuaresma-4-a-22-de-marzo-de-2020","status":"publish","type":"bible_study","link":"https:\/\/www.episcopalchurch.org\/es\/bible_study\/estudio-biblico-cuaresma-4-a-22-de-marzo-de-2020\/","title":{"rendered":"Estudio B\u00edblico: Cuaresma 4 (A) &#8211; 2020"},"content":{"rendered":"\n<hr class=\"wp-block-separator is-style-wide\" \/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Cuaresma-4A-2020-1024x536.png\" alt=\"\" class=\"wp-image-193664\" width=\"512\" height=\"268\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>1 Samuel 16: 1-13<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f3mo uno llega a asumir el papel de liderazgo es a menudo una preocupaci\u00f3n no solo en el Antiguo Testamento, sino en todo el canon de las Escrituras. A menudo, es el que menos lo espera el que asume el manto del liderazgo. Samuel asume err\u00f3neamente que el primog\u00e9nito de Jes\u00e9 va a ser el ungido. Sin embargo, en contra de las expectativas sociales de la \u00e9poca, no solo no se selecciona al hijo mayor, sino que tambi\u00e9n se pasa por alto a seis de sus hermanos menores. Se elige al m\u00e1s joven y con menos probabilidades de ser seleccionado, a pesar de la visi\u00f3n social del m\u00e9rito basada en el orden de nacimiento. \u00bfCon qu\u00e9 frecuencia pasamos por alto las posibilidades de alguien que no coincide con las expectativas de nuestra sociedad?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con una selecci\u00f3n tan decidida de David, es f\u00e1cil ver que no lleg\u00f3 al trono por casualidad. Dios elige a David, adhiri\u00e9ndose a los propios criterios de Dios para el liderazgo, a pesar de las expectativas de las cualidades de liderazgo de aquel entonces. La sociedad espera que los que son vistos como los m\u00e1s grandes lideren, mientras que los que son vistos como los menos deben seguir. \u00bfCon qu\u00e9 frecuencia se nos recuerda que los caminos de Dios no son nuestros caminos?<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>A la luz del canon de las Escrituras, \u00bfc\u00f3mo define la grandeza?<\/li><li>\u00bfC\u00f3mo concurre o discrepa su definici\u00f3n de grandeza con las opiniones de la sociedad?<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Salmo 23<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Este salmo pastoral es una opci\u00f3n popular utilizada para consolar a los afligidos en el momento de la muerte de un ser querido. Nos recuerda que el dolor es una condici\u00f3n transitoria a la que finalmente llegar\u00e1 el alivio. Hasta ese momento, mientras recorremos el camino doloroso, Dios no nos deja que lo recorramos solos. A medida que experimentamos tiempos oscuros, \u00e9l est\u00e1 all\u00ed para consolarnos y guiarnos a trav\u00e9s de ellos. \u00bfCon qu\u00e9 frecuencia confundimos al personal protector del pastor con uno del que previene el da\u00f1o, en lugar del personal de gu\u00eda que nos conduce a salir del da\u00f1o?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El favor de Dios cae igualmente en los justos que en los injustos. Una fiesta con invitados que incluye tanto a los justos como a los injustos demuestra que Dios no beneficia a unos mientras perjudica a otros. La mesa que Dios pone es para todos. Como el anfitri\u00f3n de una cena, Dios tiene una relaci\u00f3n con cada uno de nosotros, independientemente de la relaci\u00f3n que podamos tener entre nosotros. Todos somos suyos y el deseo de Dios de relacionarse con los suyos es inquebrantable. \u00bfCon qu\u00e9 frecuencia suponemos que la visi\u00f3n de Dios de los dem\u00e1s refleja la nuestra?<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfDe qu\u00e9 manera Dios nos consuela y nos gu\u00eda?<\/li><li>\u00bfC\u00f3mo el conocimiento de que Dios nos ama tanto como a aquellos que no [amamos] influye en c\u00f3mo nos comprometemos unos con otros?<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Efesios 5: 8-14<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La luz versus la oscuridad y lo nuevo versus lo viejo son contrastes dram\u00e1ticos. Enmarcar las cosas por extremos sugiere claridad m\u00e1s que oscuridad. Este pasaje establece un fuerte contraste entre la vida antigua caracterizada por las cosas valoradas por el mundo y la vida nueva caracterizada por el seguimiento de Cristo. Esta carta a los efesios establece el est\u00e1ndar de Dios y Cristo como modelos para las relaciones y conducta personales. Verdaderamente esta es una norma muy alta. En alg\u00fan momento, todos nos quedaremos cortos para dar en el blanco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto la luz como la oscuridad, lo viejo y lo nuevo requieren una observaci\u00f3n de las condiciones graduales entre ellos. Implican movimiento. Lo viejo siempre ser\u00e1 reemplazado por lo nuevo. La oscuridad siempre ser\u00e1 seguida por la luz que a su vez ser\u00e1 seguida por la oscuridad. Continuamente experimentaremos los ciclos de ambos.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfC\u00f3mo, en su viaje de fe, se da licencia para experimentar la luz y la oscuridad y los tonos de gris que existen entre ellos?<\/li><li>\u00bfC\u00f3mo retoma la meta de seguir el modelo de Dios y Cristo para las relaciones y conductas personales cuando no alcanza el objetivo?<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Juan 9: 1-41<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra relaci\u00f3n con la religi\u00f3n organizada a veces puede estar llena de dificultades. La pregunta \u201c\u00bfQui\u00e9n es el pecador?\u201d se encuentra al frente y centro en este pasaje. La b\u00fasqueda para determinar la causa de la ceguera del hombre tiene el potencial de llevarnos por una madriguera de conejo. \u00bfRealmente importa qui\u00e9n pec\u00f3 para causar la ceguera de este hombre a la luz del hecho de que el hombre tiene una necesidad que debe abordarse? Como uno que posee la imperfecci\u00f3n percibida de la ceguera, el hombre se vio obligado a existir fuera de la comunidad de culto y destinado para siempre a no ser permitido m\u00e1s all\u00e1 de las puertas de la sinagoga. El hombre ciego de la historia puede representar a la comunidad cristiana en lucha con las autoridades de la sinagoga. \u00bfCon qu\u00e9 frecuencia nuestros lugares de culto excluyen en lugar de incluir?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El miedo a ser excluido de la fraternidad de la comunidad es bastante alto. Cuando se les pregunta acerca de c\u00f3mo su hijo recuper\u00f3 la vista, los padres del hombre fingen ignorancia. Es l\u00f3gico que hubiera compartido la historia de su vista recuperada con aquellos de quienes se vio obligado a depender toda su vida. Por miedo a la exclusi\u00f3n de la comunidad de la sinagoga, en lugar de dar una respuesta, dicen: \u201cPreguntadle\u201d y, por lo tanto, condenan a su hijo al destino que tem\u00edan. \u00bfCon qu\u00e9 frecuencia nos hemos quedado callados ante la necesidad de otro porque tememos la exclusi\u00f3n?<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfDe qu\u00e9 manera nosotros, como Iglesia, exhibimos nuestra ceguera?<\/li><li>\u00bfDe qu\u00e9 manera podemos, como Iglesia, corregir los errores de hacer la vista gorda a la exclusi\u00f3n de otros?<\/li><\/ul>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Cuaresma-4A-2020.docx\"><strong>Bible-Study-Spanish-Cuaresma-4A-2020<\/strong><\/a><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Cuaresma-4A-2020.docx\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Cuaresma-4A-2020.pdf\"><strong>Bible-Study-Spanish-Cuaresma-4A-2020<\/strong><\/a><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Cuaresma-4A-2020.pdf\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>1 Samuel 16: 1-13 C\u00f3mo uno llega a asumir el papel de liderazgo es a menudo una preocupaci\u00f3n no solo en el Antiguo Testamento, sino en todo el canon de las Escrituras. A menudo, es el que menos lo espera el que asume el manto del liderazgo. Samuel asume err\u00f3neamente que el primog\u00e9nito de Jes\u00e9&#8230;<\/p>\n","protected":false},"featured_media":201220,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","ep_exclude_from_search":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[23,51,52,3],"tags":[320],"class_list":["post-768289","bible_study","type-bible_study","status-publish","has-post-thumbnail","hentry","category-bible-studies","category-lent","category-sermons-that-work","category-worship-and-prayer-menu","tag-cuaresma-4a"],"acf":[],"taxonomy_info":{"category":[{"value":23,"label":"Bible Studies"},{"value":51,"label":"Lent"},{"value":52,"label":"Sermons That Work"},{"value":3,"label":"worship_and_prayer_menu"}],"post_tag":[{"value":320,"label":"Cuaresma 4A"}]},"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study\/768289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study"}],"about":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/types\/bible_study"}],"version-history":[{"count":1,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study\/768289\/revisions"}],"predecessor-version":[{"id":952514,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study\/768289\/revisions\/952514"}],"wp:attachment":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/media?parent=768289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/categories?post=768289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/tags?post=768289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}