{"id":786640,"date":"2020-04-09T11:11:00","date_gmt":"2020-04-09T15:11:00","guid":{"rendered":"https:\/\/www2.episcopalchurch.org\/?post_type=bible_study&#038;p=186640"},"modified":"2026-06-23T18:08:56","modified_gmt":"2026-06-23T22:08:56","slug":"estudio-biblico-jueves-santo-9-de-abril-de-2020","status":"publish","type":"bible_study","link":"https:\/\/www.episcopalchurch.org\/es\/bible_study\/estudio-biblico-jueves-santo-9-de-abril-de-2020\/","title":{"rendered":"Estudio B\u00edblico: Jueves Santo &#8211; 2020"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>[RCL] \u00c9xodo 12: 1-4, (5-10), 11-14; Salmo 116: 1, 10-17; 1 Corintios 11: 23-26; Juan 13: 1-17, 31b-35<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\" \/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Jueves-Santo-2020-1024x536.png\" alt=\"\" class=\"wp-image-193771\" width=\"512\" height=\"268\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c9xodo 12: 1-4, (5-10), 11-14<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Como lo hizo saber Mois\u00e9s en la zarza ardiente, Dios ha escuchado el clamor de su pueblo en Egipto despu\u00e9s de siglos de opresi\u00f3n y ha puesto en marcha un plan de liberaci\u00f3n. Varias plagas han resultado infructuosas para doblegar el orgullo del Fara\u00f3n para liberar a los israelitas, y su imperio se ver\u00e1 afectado con la \u00faltima y m\u00e1s terrible se\u00f1al: cada hijo primog\u00e9nito en la tierra morir\u00e1 en medio de la noche. Esta tragedia sacudir\u00e1 el sistema familiar y social de Egipto en lo m\u00e1s profundo y establecer\u00e1 que el Dios de Israel es el \u00fanico Dios verdadero, cuyo poder es mayor que el atribuido a cualquier otra deidad. Pero esta noche ominosa es tambi\u00e9n el escenario para el establecimiento del pacto del Se\u00f1or con todo Israel, un cap\u00edtulo fundamental en la historia de la salvaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las instrucciones meticulosas dadas a Mois\u00e9s y Aar\u00f3n est\u00e1n dirigidas a cada hogar, cada uno de los cuales debe asegurarse un animal lo suficientemente grande como para alimentar a todos los miembros. El cordero se sacrificar\u00e1 al anochecer a una hora espec\u00edfica y luego se consumir\u00e1 en su totalidad en una comida especial antes del nuevo d\u00eda. Dios tambi\u00e9n requiere que el pan usado para esta cena sea sin levadura y que la gente participe vistiendo ropa de viaje. En esencia, los est\u00e1 preparando para un viaje lejos de la esclavitud y hacia un nuevo destino. Adem\u00e1s, el Se\u00f1or ordenar\u00e1 que se recuerde esta ocasi\u00f3n para las generaciones venideras, por lo que estas directivas son a la vez pr\u00e1cticas y ceremoniales. La Pascua es tanto el acto de ser liberado como el recuerdo de seguir contado entre los rescatados por la intervenci\u00f3n de Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de una lente cristiana, no se puede dejar de reconocer un presagio po\u00e9tico del \u00faltimo sacrificio de la cruz con la sangre del cordero sin mancha, las personas elegidas de Dios son marcadas como aquellas que no conocer\u00e1n la muerte. Por su pasi\u00f3n y muerte, Jesucristo, el Cordero de Dios, vence a la muerte y al pecado para siempre y cumple el plan del Padre de rescatar a la humanidad. En Cristo, nuestra Pascua, somos justificados y salvos de la ira de Dios (Romanos 5: 9).<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfQu\u00e9 significa vivir el pacto de Dios?<\/li><li>\u00bfQu\u00e9 puede ense\u00f1arnos el Seder de Pascua contempor\u00e1neo sobre el pacto de Dios con Israel y nuestra propia fe?<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Salmo 116: 1, 10-17<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La riqueza de este salmo radica en que es tanto una reflexi\u00f3n como una oraci\u00f3n de acci\u00f3n de gracias. El orador parece saber que la respuesta a la pregunta propuesta es simple: la bondad de Dios no se le puede pagar. Y, sin embargo, est\u00e1 impl\u00edcito que el deseo natural de alguien que ha saboreado el amor y la misericordia de Dios es ser su testigo \u201cen presencia de todo su pueblo\u201d. Al comienzo del Triduo, nos deleitamos con una vista previa de las alegr\u00edas de la Pascua, ya que ante la expectativa del triunfo de Cristo sobre la esclavitud de nuestros pecados, podemos cantar con confianza, \u201c\u00a1Aleluya!\u201d<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfOfrece usted oraciones de agradecimiento regularmente? \u00bfBusca inspiraci\u00f3n en los salmos?<\/li><li>\u00bfQu\u00e9 im\u00e1genes se evocan con las expresiones \u201cla copa de la salvaci\u00f3n\u201d y \u201clos atrios de la casa del Se\u00f1or?\u201d<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>1 Corintios 11: 23-26<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Pablo recuerda el significado de las acciones de Jes\u00fas en la \u00daltima Cena cuando reprende a los cristianos corintios que excluyen a los necesitados de sus celebraciones de comuni\u00f3n, un incidente perturbador que lo lleva a decir que lo que est\u00e1n comiendo no es la Cena del Se\u00f1or (v\u00e9ase 1 Corintios 11:20). Al repetir las palabras de Cristo sobre el pan y el vino, particularmente cuando se refiere al \u201cnuevo pacto\u201d en su sangre, el ap\u00f3stol acent\u00faa el llamado para que la Iglesia sea una comunidad. El hecho mismo de que nosotros, siguiendo el ejemplo de Jes\u00fas, nos unamos para partir el pan deber\u00eda implicar un tipo de cercan\u00eda y amistad que desaf\u00eda las divisiones mundanas. Adem\u00e1s, nuestra participaci\u00f3n en el cuerpo y la sangre de Cristo es el recuerdo del don de la redenci\u00f3n de Dios y un testimonio de su presencia entre nosotros, para que podamos, a su vez, llevar su amor a los dem\u00e1s.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfInvita a amigos o conocidos a unirse a la iglesia?<\/li><li>\u00bfCu\u00e1les son algunas formas pr\u00e1cticas de \u201cproclamar la muerte del Se\u00f1or hasta que venga\u201d en la vida cotidiana?<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Juan 13: 1-17, 31b-35<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">El vers\u00edculo inicial resume una verdad esencial de la fe cristiana: el Dios todopoderoso, en la persona de Cristo, nos ama. Independientemente de si suscribimos la teor\u00eda de que Juan es de hecho \u201cel disc\u00edpulo a quien Jes\u00fas amaba\u201d, este Evangelio est\u00e1 repleto de referencias al amor de Dios por la humanidad, alegando que incluso la entrega del Padre al Hijo se basa en ese amor. Puede ser tentador pensar en este amor como gen\u00e9rico, como, por ejemplo, el amor de un monarca por una multitud de sujetos sin nombre sin ning\u00fan tipo de contacto real. Pero si bien su amor est\u00e1 dirigido a todo el mundo, hacemos bien en prestar atenci\u00f3n a las palabras atribuidas a Agust\u00edn: \u201cDios nos ama a cada uno de nosotros como si solo fu\u00e9ramos uno de nosotros\u201d. A lo largo de su ministerio terrenal, Cristo muestra que su amor es siempre personal. Incluso en la noche de su traici\u00f3n, est\u00e1 interesado en mostrar amor a los disc\u00edpulos de una manera muy tangible: al convertirse en un siervo y lav\u00e1ndoles los pies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Qu\u00e9 impactante debe ser para ellos que el que llaman Maestro se rebaje a realizar tal tarea! Pedro est\u00e1 tan perplejo que se niega a ser lavado, pero Jes\u00fas insiste en que debe hacerlo si quiere compartir algo con \u00e9l. Hay una humildad que Jes\u00fas requiere para que \u00e9l tambi\u00e9n act\u00fae en nuestras propias vidas, pero el orgullo, en forma de culpa o sentimientos de indignidad, puede obstaculizar nuestra propia regeneraci\u00f3n por su gracia. Y a\u00fan m\u00e1s dif\u00edcil es tal vez su solicitud de que sigamos su ejemplo y nos lavemos los pies en un mundo donde aventajar a nuestros vecinos es una inclinaci\u00f3n mucho m\u00e1s popular que servirles. Pero para los cristianos, el amor no es una elecci\u00f3n. El nuevo mandamiento de Jes\u00fas lo establece como el signo de aquellos que le pertenecen y es el testimonio m\u00e1s perfecto de su Evangelio.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfCree que Dios le ama personal e \u00edntimamente?<\/li><li>\u00bfAlguna vez ha considerado ir a un viaje misionero con amigos o familiares, o comenzar usted mismo un ministerio misionero?\u200b\u200b\u200b\u200b\u200b\u200b<\/li><\/ul>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Jueves-Santo-2020.docx\"><strong>Bible-Study-Spanish-Jueves-Santo-2020<\/strong><\/a><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Jueves-Santo-2020.docx\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Jueves-Santo-2020.pdf\"><strong>Bible-Study-Spanish-Jueves-Santo-2020<\/strong><\/a><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Jueves-Santo-2020.pdf\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>[RCL] \u00c9xodo 12: 1-4, (5-10), 11-14; Salmo 116: 1, 10-17; 1 Corintios 11: 23-26; Juan 13: 1-17, 31b-35 \u00c9xodo 12: 1-4, (5-10), 11-14 Como lo hizo saber Mois\u00e9s en la zarza ardiente, Dios ha escuchado el clamor de su pueblo en Egipto despu\u00e9s de siglos de opresi\u00f3n y ha puesto en marcha un plan de&#8230;<\/p>\n","protected":false},"featured_media":201220,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","ep_exclude_from_search":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[23,36,52,1953],"tags":[296],"class_list":["post-786640","bible_study","type-bible_study","status-publish","has-post-thumbnail","hentry","category-bible-studies","category-holy-week","category-sermons-that-work","category-worship-and-prayer-menu","tag-jueves-santo"],"acf":[],"taxonomy_info":{"category":[{"value":23,"label":"Bible Studies"},{"value":36,"label":"Holy Week"},{"value":52,"label":"Sermons That Work"},{"value":1953,"label":"worship_and_prayer_menu"}],"post_tag":[{"value":296,"label":"Jueves Santo"}]},"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study\/786640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study"}],"about":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/types\/bible_study"}],"version-history":[{"count":1,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study\/786640\/revisions"}],"predecessor-version":[{"id":952685,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study\/786640\/revisions\/952685"}],"wp:attachment":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/media?parent=786640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/categories?post=786640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/tags?post=786640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}