{"id":793780,"date":"2020-04-06T21:58:52","date_gmt":"2020-04-07T01:58:52","guid":{"rendered":"https:\/\/www2.episcopalchurch.org\/bible_study\/bible-study-monday-in-holy-week-april-6-2020\/"},"modified":"2026-06-23T18:08:56","modified_gmt":"2026-06-23T22:08:56","slug":"estudio-biblico-lunes-santo-6-de-abril-de-2020","status":"publish","type":"bible_study","link":"https:\/\/www.episcopalchurch.org\/es\/bible_study\/estudio-biblico-lunes-santo-6-de-abril-de-2020\/","title":{"rendered":"Estudio B\u00edblico: Lunes Santo &#8211; 2020"},"content":{"rendered":"\n<hr class=\"wp-block-separator is-style-wide\" \/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Lunes-Santo-2020-1024x536.png\" alt=\"\" class=\"wp-image-193781\" width=\"512\" height=\"268\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Isa\u00edas 42: 1-9<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">El pasaje de Isa\u00edas 42: 1-4 es conocido como uno de los canticos del siervo sufriente, basado en una figura que aparece nuevamente en Isa\u00edas en los cap\u00edtulos 49, 50, 52 y 53. En la tradici\u00f3n cristiana, los int\u00e9rpretes han le\u00eddo este pasaje como prediciendo a Jes\u00fas, pero este tipo de lectura puede ser perjudicial, ya que a menudo borra la interpretaci\u00f3n jud\u00eda de un texto jud\u00edo. La figura del siervo sufriente ha sido interpretada en la tradici\u00f3n jud\u00eda como un rey o un profeta, pero con mayor frecuencia como la naci\u00f3n de Israel en su conjunto. Israel sufrir\u00e1 porque su pueblo trabaja por la rectitud y la justicia de Dios, pero finalmente ser\u00e1n recompensados \u200b\u200by redimidos por Dios por este trabajo. En este pasaje, despu\u00e9s de una descripci\u00f3n del liderazgo del siervo sufriente, Dios refuerza el pacto con Israel, describiendo tomar la naci\u00f3n de la mano y dando a Israel como una \u201cluz para las naciones\u201d que har\u00e1 el trabajo de Dios de liberar a aquellos que est\u00e1n presos y oprimidos. Dios ama a Israel y lo ha elegido para este prop\u00f3sito.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Jes\u00fas era jud\u00edo, y como miembro de la amada naci\u00f3n de Dios, Israel, fue llamado a la labor del liderazgo de servicio por la rectitud y la justicia. Jes\u00fas llama a sus seguidores a esta misma obra. \u00bfCu\u00e1ndo y c\u00f3mo se ha sentido usted llamado a trabajar por la justicia en nombre de otros? \u00bfC\u00f3mo fue la experiencia para usted? \u00bfC\u00f3mo fue dif\u00edcil? \u00bfC\u00f3mo fue gratificante?<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Salmo 36: 5-11<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que en la lectura del evangelio, Mar\u00eda muestra un amor extravagante por Jes\u00fas, aqu\u00ed nuestro salmista se regocija en el amor extravagante de Dios por nosotros. La hospitalidad y el amor de Dios no est\u00e1n reservados en particular para las personas en un grupo, comunidad o religi\u00f3n. La \u201cabundancia\u201d de la \u201ccasa\u201d de Dios, el amor constante de Dios y el refugio en las alas de Dios son para todas las personas. El salmista nos recuerda, adem\u00e1s, que el amor y la atenci\u00f3n ilimitados del Creador se extienden no solo a los humanos, sino a toda la creaci\u00f3n: \u201cSalvas oh Se\u00f1or, tanto a los humanos como a las bestias\u201d.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfC\u00f3mo ha presenciado o sentido el amor de Dios en su vida o en la vida de otros?<\/li><li>\u00bfCu\u00e1ndo fue un momento en el que fue dif\u00edcil sentir el amor de Dios? \u00bfCu\u00e1les son las implicaciones de que el amor de Dios no sea solo para los humanos sino para todas las criaturas vivientes?<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Hebreos 9: 11-15<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">El autor de la carta a los hebreos presenta a Cristo como sumo sacerdote real, que en lugar de sacrificar ofrendas de grano o animales, como lo hicieron los sacerdotes terrenales en el templo, se sacrifica a s\u00ed mismo en nombre de la humanidad. El amoroso sacrificio de Cristo en la cruz y la \u00faltima palabra de amor de Dios en la resurrecci\u00f3n han sido interpretados por algunos te\u00f3logos como el \u201cno\u201d de Dios al sacrificio violento. Durante la vida de Jes\u00fas, sus palabras y acciones amplifican el mensaje que Dios transmite a lo largo de la literatura prof\u00e9tica de la Biblia: \u201cDeseo misericordia, no sacrificio\u201d (Oseas 6: 6; Mateo 9:13). En su vida, muerte y resurrecci\u00f3n, Jes\u00fas abre el pacto de Dios de misericordia y amor para todos. Otra forma en que los te\u00f3logos han abordado la expiaci\u00f3n es como \u201cunificaci\u00f3n\u201d [\u201cat-one-ment\u201d]: la vida y el ministerio de auto-entrega de Jes\u00fas, su muerte y su resurrecci\u00f3n sirven para destruir el pecado y la muerte y para unirnos con Dios y con el amor de Dios por nosotros. A trav\u00e9s de esta unificaci\u00f3n, para volver a las palabras del autor de hebreos, nos sentimos motivados a responder y \u201cadorar al Dios vivo\u201d, que nos ofrece esta \u201cherencia eterna prometida\u201d de amor.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfQu\u00e9 significar\u00eda para usted pensar en la muerte y resurrecci\u00f3n de Jes\u00fas como el \u201cno\u201d de Dios a todos los sacrificios violentos? \u00bfComo la \u201cunidad de Dios\u201d con nosotros?<\/li><li>El autor de la carta a los hebreos escribe que la adoraci\u00f3n a Dios es una respuesta apropiada al sacrificio de Jes\u00fas. \u00bfC\u00f3mo podr\u00eda responder al amor de auto entrega de Jes\u00fas en su propia vida?<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Juan 12: 1-11<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">El Evangelio de Juan nos dice que antes de ir a Jerusal\u00e9n, en el camino que le llevar\u00e1 a la cruz, Jes\u00fas regresa a la casa de sus amigos Mar\u00eda, Marta y L\u00e1zaro. Jes\u00fas ama a sus tres amigos (Juan 11: 5), y est\u00e1 claro que lo aman a cambio, ya que ofrecen la hospitalidad de su hogar y su mesa. La unci\u00f3n de Mar\u00eda de los pies de Jes\u00fas es un gesto extravagante de este amor. Ofrecer hospitalidad era una pr\u00e1ctica importante en el per\u00edodo de tiempo de Jes\u00fas, y parte de la buena hospitalidad consist\u00eda en lavar los pies de los hu\u00e9spedes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda va por encima y m\u00e1s all\u00e1, ungiendo los pies de Jes\u00fas con aceite rico y fragante, y sec\u00e1ndole los pies, no con una toalla, sino con su propio cabello. \u00bfEs este amor en gratitud por el extravagante acto de amor de Jes\u00fas de traer a L\u00e1zaro de vuelta de la muerte? \u00bfEs este amor no solo de amistad sino de adoraci\u00f3n porque Mar\u00eda, como su hermana Marta (Juan 11:27), sabe que su amigo es el Hijo de Dios? \u00bfEs este amor el dolor y la pena por la muerte inminente de Jes\u00fas? El aceite se us\u00f3 (y todav\u00eda se usa) no solo para el entierro sino tambi\u00e9n para la curaci\u00f3n. \u00bfMar\u00eda unge amorosamente a Jes\u00fas, no solo como preparaci\u00f3n para su muerte, sino tambi\u00e9n como una forma de curarlo en su momento de sufrimiento? Tal vez Mar\u00eda act\u00faa de todas estas maneras de amor, un amor m\u00e1s all\u00e1 de lo que se puede decir, un amor que se expresa no con palabras, sino con las manos, el cabello, todo el cuerpo y el fuerte aroma del aceite fragante que hace memoria.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Imag\u00ednese a s\u00ed mismo en la escena de Mar\u00eda ungiendo los pies de Jes\u00fas. Lea el pasaje lentamente varias veces. \u00bfQue ve? \u00bfQu\u00e9 oye? \u00bfQu\u00e9 huele? \u00bfQu\u00e9 emociones siente?<\/li><li>Mar\u00eda muestra su amor por Jes\u00fas sin palabras. \u00bfCu\u00e1les son algunas formas en que podemos mostrar nuestro amor por Jes\u00fas hoy, con o sin palabras?\u200b\u200b\u200b\u200b\u200b\u200b<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>This Bible study, written by Melissa Howell, originally ran for Monday in Holy Week in 2019.<\/em><\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Lunes-Santo-2020.docx\"><strong>Bible-Study-Spanish-Lunes-Santo-2020<\/strong><\/a><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Lunes-Santo-2020.docx\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Lunes-Santo-2020.pdf\"><strong>Bible-Study-Spanish-Lunes-Santo-2020<\/strong><\/a><a href=\"https:\/\/www.episcopalchurch.org\/wp-content\/uploads\/2020\/11\/Bible-Study-Spanish-Lunes-Santo-2020.pdf\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Isa\u00edas 42: 1-9 El pasaje de Isa\u00edas 42: 1-4 es conocido como uno de los canticos del siervo sufriente, basado en una figura que aparece nuevamente en Isa\u00edas en los cap\u00edtulos 49, 50, 52 y 53. En la tradici\u00f3n cristiana, los int\u00e9rpretes han le\u00eddo este pasaje como prediciendo a Jes\u00fas, pero este tipo de lectura&#8230;<\/p>\n","protected":false},"featured_media":201220,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","ep_exclude_from_search":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[23,36,52,1953],"tags":[297],"class_list":["post-793780","bible_study","type-bible_study","status-publish","has-post-thumbnail","hentry","category-bible-studies","category-holy-week","category-sermons-that-work","category-worship-and-prayer-menu","tag-lunes-santo"],"acf":[],"taxonomy_info":{"category":[{"value":23,"label":"Bible Studies"},{"value":36,"label":"Holy Week"},{"value":52,"label":"Sermons That Work"},{"value":1953,"label":"worship_and_prayer_menu"}],"post_tag":[{"value":297,"label":"Lunes Santo"}]},"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study\/793780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study"}],"about":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/types\/bible_study"}],"version-history":[{"count":1,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study\/793780\/revisions"}],"predecessor-version":[{"id":952687,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/bible_study\/793780\/revisions\/952687"}],"wp:attachment":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/media?parent=793780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/categories?post=793780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/tags?post=793780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}