{"id":512652,"date":"2011-05-29T19:10:01","date_gmt":"2011-05-29T23:10:01","guid":{"rendered":""},"modified":"2026-08-09T12:29:39","modified_gmt":"2026-08-09T16:29:39","slug":"pascua-6-a-2011","status":"publish","type":"sermon","link":"https:\/\/www.episcopalchurch.org\/es\/sermons\/pascua-6-a-2011\/","title":{"rendered":"Pascua 6 (A) \u2013 2011"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><p>Vamos a comentar la bella lectura de los Hechos de los Ap\u00f3stoles. En ella san Lucas nos presenta el celo apost\u00f3lico de san Pablo y su pericia como predicador y argumentador.<\/p><br><br><p>Pablo se encontraba en Atenas, no como los turista de hoy, movido por el inter\u00e9s art\u00edstico, sino por una pasi\u00f3n: la de dar a conocer Dios en Cristo. All\u00ed esperaba a que dos disc\u00edpulos, Timoteo y Silas, llegaran por \u00e9l.<\/p><br><br><p>Es muy conocido el amor del griego a la belleza, el arte y la filosof\u00eda. Pero, adem\u00e1s, los atenienses eran religiosos. Sin embargo, Pablo \u201cestaba indignado al ver la ciudad llena de \u00eddolos\u201d. \u201cPausanias dice que Atenas ten\u00eda m\u00e1s im\u00e1genes que todo el resto de Grecia. Plinio dice que en la \u00e9poca de Ner\u00f3n Atenas ten\u00eda m\u00e1s de 30.000 estatuas p\u00fablicas, adem\u00e1s de una cantidad incalculable en las casas. Petronio se burla de que era m\u00e1s f\u00e1cil en Atenas encontrar a un dios que a un hombre\u201d.<\/p><br><br><p>Algunos fil\u00f3sofos epic\u00fareos y estoicos se acercaron a Pablo y le consideraban como un charlat\u00e1n. El fil\u00f3sofo griego Epicuro (341-270 a.d.C) hablaba de la b\u00fasqueda del placer bueno, pero sus seguidores buscaban placeres carnales. Los estoicos, seguidores del fil\u00f3sofo Zen\u00f3n (340-265 a.d C.), defend\u00edan que hab\u00eda que ser indiferentes al placer o al dolor). Estas dos escuelas de pensamiento trataban de explicar el prop\u00f3sito de la vida.<\/p><br><br><p>Con la palabra despectiva de \u201ccharlat\u00e1n\u201d acusaban a Pablo de carecer de conocimientos filos\u00f3ficos. Pero sent\u00edan curiosidad por la nueva doctrina que Pablo les pudiera exponer. Naturalmente, le trataban con cierto desprecio intelectual, porque ellos se consideran como poseedores de toda la verdad. As\u00ed que le llevaron al Are\u00f3pago para que all\u00ed expusiera su nueva doctrina. Pablo era lo que quer\u00eda. Estaba muy acostumbrado a predicar en sinagogas, ante autoridades civiles y militares, y en esta ocasi\u00f3n lo har\u00eda ante los m\u00e1s sofisticados griegos.<\/p><br><br><p>Pablo inicia su discurso muy diplom\u00e1ticamente y les alaba de esta manera: \u201cVeo que sois muy religiosos\u201d. Pablo no manifiesta el enfado que tiene en su interior ante gente que, siendo por una parte amantes de la filosof\u00eda, por otra, hab\u00edan ca\u00eddo en tanta idolatr\u00eda.<\/p><br><br><p>Y contin\u00faa: \u201cestando yo paseando y mirando vuestros santuarios encontr\u00e9 un altar con esta inscripci\u00f3n: AL DIOS NO CONOCIDO\u201d. Yo vengo a anunciaros a ese Dios que ador\u00e1is ya, sin conocerlo.<\/p><br><br><p>Los atenienses ten\u00edan miedo de ser castigados por alg\u00fan dios a quien no conocieran; por eso erig\u00edan altares \u201cal Dios no conocido\u201d. Durante una plaga Epim\u00e9nides aconsej\u00f3 el sacrificio de una oveja al dios apropiado, quienquiera que fuera. No quer\u00edan que se les escapara ning\u00fan dios.<\/p><br><br><p>Para evitar ser castigado por la ley romana que prohib\u00eda la introducci\u00f3n de nuevos dioses, Pablo dice a los atenienses que ya est\u00e1n adorando al verdadero Dios. No introduce ning\u00fan dios nuevo. Y contin\u00faa de esta manera: ese dios desconocido es \u201cel Dios que hizo el mundo y todo lo que hay en \u00e9l\u201d (Hechos 17:24). Ese Dios es el \u00fanico Dios vivo; en otras palabras, no existe \u201cel dios sol\u201d, \u201cel dios luna\u201d, \u201cel dios mar\u201d, etc., sino que hay un solo Dios que da vida a todo.<\/p><br><br><p>Los fil\u00f3sofos griegos rechazaban la creaci\u00f3n especial por alg\u00fan dios. Sin embargo, Pablo la afirma, y no solamente Dios es el Creador sino que tambi\u00e9n es el gobernador de todo lo que existe. Y, en realidad, no necesita de nadie porque todos hemos sido creados por \u00e9l, y a su imagen. Dios cre\u00f3 a la primera pareja de la cual han procedido todas las naciones del mundo. Esta idea choc\u00f3 contra el orgullo vano de los atenienses, pues se cre\u00edan superiores a los dem\u00e1s. Para Pablo todo se encuentra bajo el ojo universal de Dios: las fronteras de las naciones, las etapas de la historia, todo est\u00e1 bajo el dominio de Dios. Dios hace lo que los dioses nacionales de los griegos no hac\u00edan: gobernar el mundo.<\/p><br><br><p>M\u00e1s a\u00fan, Dios est\u00e1 al alcance de todos. El objetivo final de Dios es que todos lo encuentren, incluso si caminamos a ciegas, palpando, lo podemos encontrar. La felicidad de los humanos no se encuentra en ning\u00fan placer creado, como ense\u00f1aban los epic\u00fareos, ni en la indiferencia hacia el placer y el dolor, como ense\u00f1aban los estoicos, sino en la b\u00fasqueda y el conocimiento de Dios. Es natural que los seres humanos busquemos a Dios, porque Dios es el Creador de todos. Muchos creyeron haber encontrado a Dios en la naturaleza y adoraron al sol, a la luna, a las estrellas y animales (Romanos 1:23-25).<\/p><br><br><p>Pablo va todav\u00eda mucho m\u00e1s lejos, no solamente buscamos a Dios sino que \u201cen \u00e9l vivimos, y nos movemos, y existimos\u201d (Hechos 17:28). Esta es la prueba de que Dios no est\u00e1 lejos de nosotros. De hecho, dependemos totalmente de Dios; sin \u00e9l, no podemos vivir, ser\u00edamos reducidos a la nada. Pero, todav\u00eda hay m\u00e1s; dice Pablo: \u201ccomo algunos de vuestros propios poetas tambi\u00e9n han dicho: \u00b4 Porque somos tambi\u00e9n de su linaje \u00b4\u201d (Hechos 17:28). Es una cita del poeta Arato (270 a. de C.), nativo de Cilicia, el pa\u00eds de Pablo. Los que escuchaban a Pablo en el Are\u00f3pago pod\u00edan constatar ahora que Pablo no era un \u201ccharlat\u00e1n\u201d, sino un hombre de letras. Siendo, pues, de linaje o de naturaleza divina, no debemos pensar que la divinidad sea semejante al oro, a la plata o a cualquier escultura de arte. Estos materiales se usaban para hacer estatuas para los dioses de Atenas. Todos sabemos que los hijos se parecen a sus padres; por eso, si los seres humanos no tienen una naturaleza de metales preciosos y si los seres humanos son del linaje de Dios, entonces Dios tampoco tiene la naturaleza de esos materiales.<\/p><br><br><p>La triste verdad es que los id\u00f3latras rechazaban la frase de G\u00e9nesis (G\u00e9nesis1:26) donde se afirma que el ser humano fue hecho a la imagen de Dios. Los id\u00f3latras creaban una imagen de Dios a la medida de sus intereses humanos.<\/p><br><br><p>Pero Dios, habiendo pasado por alto los tiempos de la ignorancia, exige ahora la conversi\u00f3n de todos. Cuando Pablo habl\u00f3 de la ignorancia de los atenienses, \u00e9stos no pod\u00edan quejarse, porque ellos mismos hab\u00edan erigido un altar con la inscripci\u00f3n, \u201cAL DIOS NO CONOCIDO\u201d. Este Dios no conocido, exige la conversi\u00f3n. Los dioses paganos no exig\u00edan la conversi\u00f3n o el arrepentimiento porque eran peores que sus adoradores, pero el verdadero Dios s\u00ed demanda que todos se arrepientan.<\/p><br><br><p>Dios requiere que los fil\u00f3sofos griegos se arrepientan. Los dioses hechos por los hombres \u2013 hechos a la imagen del hombre \u2013 nunca exigen el arrepentimiento. \u00bfPor qu\u00e9 iba el hombre a inventar un dios que le condenara? No tiene sentido hacerlo. S\u00f3lo el Dios vivo exige el arrepentimiento. Y la prueba final de la necesidad de la conversi\u00f3n es que a todos nos medir\u00e1 por el ejemplo de Cristo que muri\u00f3 por nosotros y ha sido resucitado por el Dios vivo y verdadero.<\/p><br><br><p>Pero cuando oyeron a Pablo hablar de la resurrecci\u00f3n de los muertos, unos se burlaban de \u00e9l y otros dec\u00edan: \u201cYa te oiremos acerca de esto otra vez\u201d (Hechos17:32). Es decir, no estaban preparados para aceptar en pleno el mensaje cristiano. Sin embargo, algunos de los que oyeron su discurso se convirtieron, entre ellos Dionisio el areopagita, una mujer llamada Damaris y algunos otros entre ellos.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Este serm\u00f3n fue escrito por <strong>el Rvdo. Isa\u00edas A. Rodr\u00edguez<\/strong>.<br><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vamos a comentar la bella lectura de los Hechos de los Ap\u00f3stoles. En ella san Lucas nos presenta el celo apost\u00f3lico de san Pablo y su pericia como predicador y argumentador. Pablo se encontraba en Atenas, no como los turista de hoy, movido por el inter\u00e9s art\u00edstico, sino por una pasi\u00f3n: la de dar a&#8230;<\/p>\n","protected":false},"featured_media":201217,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","ep_exclude_from_search":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[43,52],"tags":[],"class_list":["post-512652","sermon","type-sermon","status-publish","has-post-thumbnail","hentry","category-sermons","category-sermons-that-work"],"acf":[],"taxonomy_info":{"category":[{"value":43,"label":"Sermons"},{"value":52,"label":"Sermons That Work"}]},"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/sermon\/512652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/sermon"}],"about":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/types\/sermon"}],"version-history":[{"count":2,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/sermon\/512652\/revisions"}],"predecessor-version":[{"id":3477106,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/sermon\/512652\/revisions\/3477106"}],"wp:attachment":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/media?parent=512652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/categories?post=512652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/tags?post=512652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}