{"id":512683,"date":"2010-12-25T19:33:36","date_gmt":"2010-12-26T00:33:36","guid":{"rendered":""},"modified":"2026-08-10T09:24:40","modified_gmt":"2026-08-10T13:24:40","slug":"navidad-i-2010","status":"publish","type":"sermon","link":"https:\/\/www.episcopalchurch.org\/es\/sermons\/navidad-i-2010\/","title":{"rendered":"Navidad (I) \u2013 2010"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><p>\u00a1Feliz Navidad! Este es un d\u00eda de j\u00fabilo en la cristiandad. Tras semanas de preparaci\u00f3n, de grandes expectativas, por fin lleg\u00f3 el momento. Ha nacido el ni\u00f1o. Ha nacido el Ni\u00f1o Dios.<\/p><br><br><p>En muchos hogares a esta hora ya hay una monta\u00f1a de papel de regalos, de cajas y envolturas desechadas a la carrera. Con gran esmero envolvimos los regalos para las personas que tanto queremos y hoy, todo lo que promet\u00edan esos regalos colocados al lado del pesebre o bajo el arbolito de navidad, todo ese misterio ya qued\u00f3 resuelto. Lo que recibimos y lo que dimos tal vez encant\u00f3, tal vez desilusion\u00f3, pero ya sabemos lo que es, ya qued\u00f3 en claro lo que iba a ser esta Navidad en lo que se refiere al dar y al recibir.<\/p><br><br><p>Por lo menos, es as\u00ed como una cultura de consumismo quiere que entendamos la Navidad. Si no quedamos satisfechos con nuestros regalos, el a\u00f1o entrante volveremos a ensayar, y trataremos de dar algo mejor. Secretamente le pediremos a las fuerzas del universo que nuestro marido o nuestra esposa nos entienda lo suficientemente bien para que nos d\u00e9 el regalo perfecto y no otra corbata o m\u00e1quina de coser. La tentaci\u00f3n al terminar de abrir los regalos de Navidad es pensar que ya recibimos todo lo que \u00edbamos a recibir. Pero nos equivocamos si lo vemos as\u00ed.<\/p><br><br><p>Nos hemos congregado en este lugar porque, aunque nos hayamos entregado por completo al traj\u00edn de la Navidad seg\u00fan lo que dicta nuestra cultura, sabemos que nos hace falta algo m\u00e1s. Aunque tengamos un carro Mazeratti nuevo en el garaje y un diamante de 15 quilates, hay algo muy por dentro de nuestro coraz\u00f3n que queda vac\u00edo y que a\u00fan espera. Hay algo m\u00e1s profundo que a\u00f1oramos recibir.<\/p><br><br><p>Para los inmigrantes de primera generaci\u00f3n, tal vez el vac\u00edo que se siente sea el dolor de patria. Las celebraciones y costumbres que formaron la ni\u00f1ez, los paisajes, los olores y los sonidos de Navidad en la tierra natal brillan por su ausencia. A lo mejor tambi\u00e9n hay parientes, primos y t\u00edos, hermanos, inclusive los propios padres, que est\u00e1n ausentes esta Navidad. Esa ausencia tambi\u00e9n forma parte del vac\u00edo. Ni el tequila, ni el ron logran borrar por completo esos rastros de otro mundo que una vez se vivi\u00f3 y que hoy tristemente est\u00e1 lejos.<\/p><br><br><p>Para otros que ya somos parte de la segunda, la tercera, o cuarta generaci\u00f3n en este pa\u00eds, tal vez sentimos esos vac\u00edos por otras razones\u2014porque en esta econom\u00eda es tan dif\u00edcil encontrar un buen trabajo y la angustia de construir un futuro para nuestros hijos es tan grande. O porque nuestra familia tiene sus conflictos y fragilidades que nos hacen sentir inseguros y solos. O porque las noticias todos los d\u00edas son tan negativas, sale de nuestro coraz\u00f3n la oraci\u00f3n: \u201cDios m\u00edo, es tan peque\u00f1a mi barca y el mar es tan grande\u201d.<\/p><br><br><p>Los regalos nos encanta darlos, nos encanta recibirlos y con todo y eso, no nos brindan la plenitud de vida que los comerciales siempre andan prometiendo. A veces lo olvidamos pero nuestros corazones lo saben y por eso nos hemos congregado hoy. Sabemos que el verdadero regalo es otro. Y sabemos tambi\u00e9n que Dios lo que m\u00e1s quiere es darnos precisamente lo que m\u00e1s a\u00f1ora nuestro ser: el regalo de vida nueva en Jesucristo.<\/p><br><br><p>Hoy estamos aqu\u00ed para recibir ese regalo y vale la pena detenernos unos instantes a ponderar lo que estamos queriendo recibir.<\/p><br><br><p>La proclamaci\u00f3n del \u00e1ngel nos ayuda a comprender lo que buscamos. Dice el \u00e1ngel: \u201cHoy, en la ciudad de David, ha nacido para ustedes un Salvador, que es el Mes\u00edas y el Se\u00f1or\u201d. \u00bfPor qu\u00e9 ser\u00e1 que Lucas lo presenta de esta manera? Hubiera sido suficiente proclamar que \u201choy en la ciudad de David ha nacido un Salvador\u201d. Pero Lucas dice que ha nacido este ni\u00f1o para nosotros. Vivimos en un mundo que se olvida de nuestra particularidad, de nuestra humanidad. Si vamos al supermercado a comprar jam\u00f3n nos dicen que saquemos n\u00famero y no nos llaman por nombre sino que cuando ya nos toca nuestro turno, alguien grita el n\u00famero. Piensen en cu\u00e1ntas situaciones es m\u00e1s importante tener n\u00famero de seguridad social que tener nombre. Cu\u00e1ntas veces nos toca entrar en un lugar lleno de gente donde nadie nos conoce y no conocemos un alma.<\/p><br><br><p>El Evangelio de Lucas nos dice que ha nacido un ni\u00f1o para nosotros\u2014para cada uno de nosotros en toda nuestra singularidad. Hemos sido conocidos por Dios desde el momento de nuestra creaci\u00f3n y Dios conoce las fortalezas y las debilidades que cada cual lleva por dentro. Su hijo, el ni\u00f1o Dios, viene a elevar lo que es bueno y fuerte en nuestro ser y a sanar y reconciliar lo que est\u00e1 maltratado, desfigurado y quebrantado por el pecado.<\/p><br><br><p>Aunque le estamos m\u00e1s atentos a \u00e9l en esta ocasi\u00f3n, el regalo de vida nueva en el ni\u00f1o Dios lo recibimos una y otra vez, en los momentos y los lugares m\u00e1s inesperados. Considera este a\u00f1o que ya est\u00e1 terminando. \u00bfEn qu\u00e9 momentos enfrentaste una situaci\u00f3n que no parec\u00eda tener soluci\u00f3n y de pronto te diste cuenta de una respuesta totalmente nueva que brind\u00f3 nuevas esperanzas? La vida nueva, la vida abundante en Cristo sale a nuestro encuentro inclusive en los momentos m\u00e1s dif\u00edciles de nuestro existir.<\/p><br><br><p>El regalo que recibimos por parte de Dios muchas veces interrumpe nuestros planes y abre horizontes que jam\u00e1s hubi\u00e9ramos considerado. \u00bfQui\u00e9n iba a pensar que ese ni\u00f1ito de familia tan humilde y marginada era el Mes\u00edas? Cuando Dios se hace carne, cuando viene a morar entre nosotros, consagra todas nuestras vidas, nos invita a todos a vivir con \u00e9l y a participar en un reinado de amor, justicia y misericordia.<\/p><br><br><p>El regalo que Dios se muere por ofrecernos es de valor infinito. Podr\u00edamos pasarnos el resto de la vida ponderando lo que Dios nos ha ofrecido y no agotar\u00edamos el misterio de su encarnaci\u00f3n. Vino a entregarse al mundo, a servir al mundo con una humildad absoluta. Es Dios mismo el que yace en ese pesebre. Dios se subyug\u00f3, se hizo hombre para estar con nosotros. No hay palabras suficientes para captar todo lo que significa este regalo.<\/p><br><br><p>\u00bfQu\u00e9 podremos hacer para merecer tanta generosidad? Nada. Absolutamente nada. No se trata de algo que podamos comprar o merecer. Dios no pone condiciones para darnos su amor.<\/p><br><br><p>Si bien es cierto que no podemos hacer nada para merecernos ese amor, s\u00ed tenemos que acercarnos a recibirlo. Dios no nos obliga. S\u00f3lo nos invita a venir a Bel\u00e9n a ver esa criatura reci\u00e9n nacida. Dios no se impone en nuestras vidas, pero s\u00ed abre puertas y ventanas y nos reta a verlo a \u00e9l, a nuestro pr\u00f3jimo y a toda la creaci\u00f3n con ojos generosos, corazones reconciliadores, manos extendidas para sanar y servir. Dios nos convierte en regalo porque amor que no se regala no es verdadero amor.<\/p><br><br><p>Hay tant\u00edsimas personas en el mundo, en nuestra comunidad, en nuestro vecindario que se han quedado sin este regalo esta Navidad. Gocemos juntos un ratico porque una vez m\u00e1s ha nacido Dios en nuestros corazones. Y luego salgamos al mundo y con nuestras obras y voces proclamemos, \u201choy, en la ciudad de David, ha nacido para ustedes un Salvador, que es el Mes\u00edas y el Se\u00f1or\u201d.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Este serm\u00f3n fue escrito por <\/em><strong><em>Julio Lema<\/em><\/strong><em>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Feliz Navidad! Este es un d\u00eda de j\u00fabilo en la cristiandad. Tras semanas de preparaci\u00f3n, de grandes expectativas, por fin lleg\u00f3 el momento. Ha nacido el ni\u00f1o. Ha nacido el Ni\u00f1o Dios. En muchos hogares a esta hora ya hay una monta\u00f1a de papel de regalos, de cajas y envolturas desechadas a la carrera. Con&#8230;<\/p>\n","protected":false},"featured_media":201217,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","ep_exclude_from_search":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[16,43,52,3],"tags":[464],"class_list":["post-512683","sermon","type-sermon","status-publish","has-post-thumbnail","hentry","category-christmas","category-sermons","category-sermons-that-work","category-worship-and-prayer-menu","tag-dia-de-navidad-i"],"acf":[],"taxonomy_info":{"category":[{"value":16,"label":"Christmas"},{"value":43,"label":"Sermons"},{"value":52,"label":"Sermons That Work"},{"value":3,"label":"worship_and_prayer_menu"}],"post_tag":[{"value":464,"label":"D\u00eda de Navidad I"}]},"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/sermon\/512683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/sermon"}],"about":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/types\/sermon"}],"version-history":[{"count":2,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/sermon\/512683\/revisions"}],"predecessor-version":[{"id":3477213,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/sermon\/512683\/revisions\/3477213"}],"wp:attachment":[{"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/media?parent=512683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/categories?post=512683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.episcopalchurch.org\/es\/wp-json\/wp\/v2\/tags?post=512683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}